{"id":154,"count":1,"description":"","link":"https:\/\/www.bennett-travel.com\/blog\/tag\/cultural-education\/","name":"Cultural Education","slug":"cultural-education","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cultural Education Archives - Bennett Travel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bennett-travel.com\/blog\/tag\/cultural-education\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cultural Education Archives - Bennett Travel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bennett-travel.com\/blog\/tag\/cultural-education\/\" \/>\n<meta property=\"og:site_name\" content=\"Bennett Travel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/tag\\\/cultural-education\\\/\",\"url\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/tag\\\/cultural-education\\\/\",\"name\":\"Cultural Education Archives - Bennett Travel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/tag\\\/cultural-education\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/tag\\\/cultural-education\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cultural Education\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/\",\"name\":\"Bennett Travel\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/#organization\",\"name\":\"Bennett Travel\",\"url\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Screenshot-2023-04-19-at-10.53.13-AM.png\",\"contentUrl\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Screenshot-2023-04-19-at-10.53.13-AM.png\",\"width\":1698,\"height\":1456,\"caption\":\"Bennett Travel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bennett-travel.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BennettTravel1\",\"https:\\\/\\\/www.instagram.com\\\/bennett_travel1\\\/\",\"https:\\\/\\\/linkedin.com\\\/company\\\/bennett-travel\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cultural Education Archives - Bennett Travel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bennett-travel.com\/blog\/tag\/cultural-education\/","og_locale":"en_US","og_type":"article","og_title":"Cultural Education Archives - Bennett Travel","og_url":"https:\/\/www.bennett-travel.com\/blog\/tag\/cultural-education\/","og_site_name":"Bennett Travel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bennett-travel.com\/blog\/tag\/cultural-education\/","url":"https:\/\/www.bennett-travel.com\/blog\/tag\/cultural-education\/","name":"Cultural Education Archives - Bennett Travel","isPartOf":{"@id":"https:\/\/www.bennett-travel.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.bennett-travel.com\/blog\/tag\/cultural-education\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bennett-travel.com\/blog\/tag\/cultural-education\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bennett-travel.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Cultural Education"}]},{"@type":"WebSite","@id":"https:\/\/www.bennett-travel.com\/blog\/#website","url":"https:\/\/www.bennett-travel.com\/blog\/","name":"Bennett Travel","description":"","publisher":{"@id":"https:\/\/www.bennett-travel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bennett-travel.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bennett-travel.com\/blog\/#organization","name":"Bennett Travel","url":"https:\/\/www.bennett-travel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bennett-travel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.bennett-travel.com\/blog\/wp-content\/uploads\/2023\/04\/Screenshot-2023-04-19-at-10.53.13-AM.png","contentUrl":"https:\/\/www.bennett-travel.com\/blog\/wp-content\/uploads\/2023\/04\/Screenshot-2023-04-19-at-10.53.13-AM.png","width":1698,"height":1456,"caption":"Bennett Travel"},"image":{"@id":"https:\/\/www.bennett-travel.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BennettTravel1","https:\/\/www.instagram.com\/bennett_travel1\/","https:\/\/linkedin.com\/company\/bennett-travel"]}]}},"_links":{"self":[{"href":"https:\/\/www.bennett-travel.com\/blog\/wp-json\/wp\/v2\/tags\/154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bennett-travel.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.bennett-travel.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.bennett-travel.com\/blog\/wp-json\/wp\/v2\/posts?tags=154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}